{"id":152,"count":1,"description":"","link":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/","name":"vuelos directos","slug":"vuelos-directos","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>vuelos directos archivos - La C&aacute;psula Viajera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vuelos directos archivos - La C&aacute;psula Viajera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/\" \/>\n<meta property=\"og:site_name\" content=\"La C&aacute;psula Viajera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/tag\\\/vuelos-directos\\\/\",\"url\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/tag\\\/vuelos-directos\\\/\",\"name\":\"vuelos directos archivos - La C&aacute;psula Viajera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/tag\\\/vuelos-directos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/tag\\\/vuelos-directos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"vuelos directos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/#website\",\"url\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/\",\"name\":\"La C&aacute;psula Viajera\",\"description\":\"Escucha la Actualidad Tur&iacute;stica y Ponte al d&iacute;a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lacapsuladelacreatividad.info\\\/capviajera\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"vuelos directos archivos - La C&aacute;psula Viajera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/","og_locale":"es_ES","og_type":"article","og_title":"vuelos directos archivos - La C&aacute;psula Viajera","og_url":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/","og_site_name":"La C&aacute;psula Viajera","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/","url":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/","name":"vuelos directos archivos - La C&aacute;psula Viajera","isPartOf":{"@id":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/#website"},"breadcrumb":{"@id":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/tag\/vuelos-directos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/"},{"@type":"ListItem","position":2,"name":"vuelos directos"}]},{"@type":"WebSite","@id":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/#website","url":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/","name":"La C&aacute;psula Viajera","description":"Escucha la Actualidad Tur&iacute;stica y Ponte al d&iacute;a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/wp-json\/wp\/v2\/tags\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lacapsuladelacreatividad.info\/capviajera\/wp-json\/wp\/v2\/posts?tags=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}